{"id":57,"date":"2013-08-21T19:03:41","date_gmt":"2013-08-21T17:03:41","guid":{"rendered":"https:\/\/bsc-srl.it\/cms\/?page_id=57"},"modified":"2022-07-13T14:43:18","modified_gmt":"2022-07-13T12:43:18","slug":"riduzione-volumetrica-e-smaltimento-rifiuti-cimiteriali","status":"publish","type":"page","link":"https:\/\/bsc-srl.it\/cms\/riduzione-volumetrica-e-smaltimento-rifiuti-cimiteriali\/","title":{"rendered":"Riduzione Volumetrica e smaltimento rifiuti cimiteriali"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.17.4&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_type=&#8221;circular&#8221; background_color_gradient_direction_radial=&#8221;top left&#8221; background_color_gradient_stops=&#8221;rgba(0,79,140,0.34) 0%|rgba(0,56,94,0.75) 50%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,79,140,0.34)&#8221; background_color_gradient_end=&#8221;rgba(0,56,94,0.75)&#8221; background_color_gradient_end_position=&#8221;50%&#8221; background_image=&#8221;https:\/\/bsc-srl.it\/cms\/wp-content\/uploads\/2021\/02\/outdoor-05.jpg&#8221; parallax=&#8221;on&#8221; custom_padding=&#8221;10vh|0|0||false|false&#8221; custom_padding_tablet=&#8221;10vh||10vh||false&#8221; custom_padding_phone=&#8221;5vh||5vh||false&#8221; box_shadow_style=&#8221;preset7&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;-100px&#8221; box_shadow_color=&#8221;#ffffff&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; text_color=&#8221;light&#8221; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;Vollkorn||||||||&#8221; title_font_size=&#8221;53px&#8221; title_font_size_tablet=&#8221;50px&#8221; title_font_size_phone=&#8221;43px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0|0px|19px|0px|false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_delay=&#8221;400ms&#8221; animation_intensity_slide=&#8221;2%&#8221; use_custom_width=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_divider color=&#8221;rgba(255,255,255,0.2)&#8221; divider_position=&#8221;bottom&#8221; divider_weight=&#8221;2px&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_button button_url=&#8221;tel:+393458849396&#8243; button_text=&#8221;Mattia Cantamessa&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.17.4&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;13px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#1e4278&#8243; button_border_width=&#8221;0px&#8221; button_border_color=&#8221;rgba(0,0,0,0)&#8221; button_border_radius=&#8221;100px&#8221; button_letter_spacing=&#8221;1px&#8221; button_font=&#8221;Libre Franklin|600|||||||&#8221; button_icon=&#8221;&#xe090;||divi||400&#8243; button_icon_placement=&#8221;left&#8221; button_on_hover=&#8221;off&#8221; background_layout=&#8221;dark&#8221; custom_padding=&#8221;16px|26px|16px|44px|true|false&#8221; button_letter_spacing_hover=&#8221;1px&#8221; button_bg_color_hover=&#8221;#236299&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;1px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;#236299&#8243; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.17.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; header_4_line_height=&#8221;1.3em&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h4 style=\"text-align: justify;\">Altre ai servizi specifici della gestione dei cimiteri, Bergamo Servizi Cimiteriali garantisce dal 2010 il\u00a0<strong>trasporto\u00a0<\/strong>e lo\u00a0<strong>smaltimento\u00a0<\/strong>dei <strong>rifiuti<\/strong>.<\/h4>\n<h4 style=\"text-align: justify;\">Richiesto dalle amministrazioni, soprattutto a seguito delle operazioni di esumazione ed estumulazione, il servizio necessita di particolare cura e consiste in:<\/h4>\n<h4>\u2022 identificare correttamente con adeguato\u00a0codice CER\u00a0tutte le sostanze e i materiali rinvenuti, non attribuibili a resti mortali, con particolare riferimento ad assi e resti delle casse utilizzate per la sepoltura, simboli religiosi, piedini, ornamenti e mezzi di movimentazione della cassa, avanzi di indumenti, imbottiture e similari, resti non mortali di elementi biodegradabili inseriti nel cofano, resti metallici di casse come zinco e\u00a0 piombo;<\/h4>\n<h4>\u2022 raccogliere i rifiuti rinvenuti posizionandoli in appositi imballaggi e contenitori da depositare in apposita area confinata;<\/h4>\n<h4>\u2022 trasportare e avviare a recupero e\/o smaltimento i suddetti rifiuti in impianti autorizzati. Ogni viaggio deve essere accompagnato dal Formulario\u00a0di\u00a0Identificazione Rifiuti, come previsto dal D.Lgs. 152\/2006, correttamente compilato in ogni sua parte con particolare riferimento a data, ora, descrizione del rifiuto trasportato (comprensivo di CER ed eventuali caratteristiche di pericolo), provenienza, destinazione e targa dell\u2019automezzo;<\/h4>\n<h4>\u2022 provvedere alla fornitura, vidimazione, compilazione e conservazione del Registro di carico e scarico dei rifiuti e dei Formulari di Identificazione Rifiuti necessari per ogni trasporto.<\/h4>\n<h4 style=\"text-align: justify;\"><strong><a href=\"https:\/\/bsc-srl.it\/cms\/contatti\/\" target=\"_blank\" rel=\"noopener\">Richiedi il nostro intervento<\/a><\/strong><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Altre ai servizi specifici della gestione dei cimiteri, Bergamo Servizi Cimiteriali garantisce dal 2010 il\u00a0trasporto\u00a0e lo\u00a0smaltimento\u00a0dei rifiuti. Richiesto dalle amministrazioni, soprattutto a seguito delle operazioni di esumazione ed estumulazione, il servizio necessita di particolare cura e consiste in: \u2022 identificare correttamente con adeguato\u00a0codice CER\u00a0tutte le sostanze e i materiali rinvenuti, non attribuibili a resti mortali, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<h4 style=\"text-align: justify;\">Altre ai servizi specifici della gestione dei cimiteri, Bergamo Servizi Cimiteriali garantisce dal 2010 il\u00a0<strong>trasporto\u00a0<\/strong>e lo\u00a0<strong>smaltimento\u00a0<\/strong>dei<strong>rifiuti<\/strong>.\u00a0Richiesto dalle amministrazioni, soprattutto a seguito delle operazioni di esumazione ed estumulazione, il servizio necessita di particolare cura e consiste in:\r\n\r\n\u2022 identificare correttamente con adeguato\u00a0<strong>codice CER<\/strong>\u00a0tutte le sostanze e i materiali rinvenuti, non attribuibili a resti mortali, con particolare riferimento ad assi e resti delle casse utilizzate per la sepoltura, simboli religiosi, piedini, ornamenti e mezzi di movimentazione della cassa, avanzi di indumenti, imbottiture e similari, resti non mortali di elementi biodegradabili inseriti nel cofano, resti metallici di casse come zinco e\u00a0 piombo;\r\n\r\n\u2022 raccogliere i rifiuti rinvenuti posizionandoli in appositi imballaggi e contenitori da depositare in apposita area confinata;\r\n\r\n\u2022 trasportare e avviare a recupero e\/o smaltimento i suddetti rifiuti in impianti autorizzati. Ogni viaggio deve essere accompagnato dal<strong>Formulario\u00a0<\/strong>di\u00a0<strong>Identificazione Rifiuti<\/strong>, come previsto dal D.Lgs. 152\/2006, correttamente compilato in ogni sua parte con particolare riferimento a data, ora, descrizione del rifiuto trasportato (comprensivo di CER ed eventuali caratteristiche di pericolo), provenienza, destinazione e targa dell\u2019automezzo;\r\n\r\n\u2022 provvedere alla fornitura, vidimazione, compilazione e conservazione del Registro di carico e scarico dei rifiuti e dei Formulari di Identificazione Rifiuti necessari per ogni trasporto.<\/h4>\r\n<h4 style=\"text-align: justify;\"><a href=\"https:\/\/www.bsc-srl.it\/LinkClick.aspx?link=60&tabid=65\" target=\"_blank\">Richiedi il nostro intervento<\/a>\u00a0<img alt=\"\" src=\"https:\/\/www.bsc-srl.it\/Portals\/0\/immagini\/LOGHINO.png\" width=\"50\" height=\"46\" \/><\/h4>","_et_gb_content_width":"","footnotes":""},"class_list":["post-57","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riduzione Volumetrica e smaltimento rifiuti cimiteriali - bsc-srl.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bsc-srl.it\/cms\/smaltimento-rifiuti-cimiteriali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riduzione Volumetrica e smaltimento rifiuti cimiteriali - bsc-srl.it\" \/>\n<meta property=\"og:description\" content=\"Altre ai servizi specifici della gestione dei cimiteri, Bergamo Servizi Cimiteriali garantisce dal 2010 il\u00a0trasporto\u00a0e lo\u00a0smaltimento\u00a0dei rifiuti. Richiesto dalle amministrazioni, soprattutto a seguito delle operazioni di esumazione ed estumulazione, il servizio necessita di particolare cura e consiste in: \u2022 identificare correttamente con adeguato\u00a0codice CER\u00a0tutte le sostanze e i materiali rinvenuti, non attribuibili a resti mortali, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bsc-srl.it\/cms\/smaltimento-rifiuti-cimiteriali\/\" \/>\n<meta property=\"og:site_name\" content=\"bsc-srl.it\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-13T12:43:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bsc-srl.it\/Portals\/0\/immagini\/LOGHINO.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/smaltimento-rifiuti-cimiteriali\\\/\",\"url\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/smaltimento-rifiuti-cimiteriali\\\/\",\"name\":\"Riduzione Volumetrica e smaltimento rifiuti cimiteriali - bsc-srl.it\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/#website\"},\"datePublished\":\"2013-08-21T17:03:41+00:00\",\"dateModified\":\"2022-07-13T12:43:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/smaltimento-rifiuti-cimiteriali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/smaltimento-rifiuti-cimiteriali\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/smaltimento-rifiuti-cimiteriali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Smaltimento rifiuti cimiteriali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/\",\"name\":\"bsc-srl.it\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/#organization\",\"name\":\"Bergamo servizi cimiteriali\",\"url\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/bsc-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/bsc-logo-1.png\",\"width\":261,\"height\":106,\"caption\":\"Bergamo servizi cimiteriali\"},\"image\":{\"@id\":\"https:\\\/\\\/bsc-srl.it\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riduzione Volumetrica e smaltimento rifiuti cimiteriali - bsc-srl.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bsc-srl.it\/cms\/smaltimento-rifiuti-cimiteriali\/","og_locale":"it_IT","og_type":"article","og_title":"Riduzione Volumetrica e smaltimento rifiuti cimiteriali - bsc-srl.it","og_description":"Altre ai servizi specifici della gestione dei cimiteri, Bergamo Servizi Cimiteriali garantisce dal 2010 il\u00a0trasporto\u00a0e lo\u00a0smaltimento\u00a0dei rifiuti. Richiesto dalle amministrazioni, soprattutto a seguito delle operazioni di esumazione ed estumulazione, il servizio necessita di particolare cura e consiste in: \u2022 identificare correttamente con adeguato\u00a0codice CER\u00a0tutte le sostanze e i materiali rinvenuti, non attribuibili a resti mortali, [&hellip;]","og_url":"https:\/\/bsc-srl.it\/cms\/smaltimento-rifiuti-cimiteriali\/","og_site_name":"bsc-srl.it","article_modified_time":"2022-07-13T12:43:18+00:00","og_image":[{"url":"https:\/\/www.bsc-srl.it\/Portals\/0\/immagini\/LOGHINO.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bsc-srl.it\/cms\/smaltimento-rifiuti-cimiteriali\/","url":"https:\/\/bsc-srl.it\/cms\/smaltimento-rifiuti-cimiteriali\/","name":"Riduzione Volumetrica e smaltimento rifiuti cimiteriali - bsc-srl.it","isPartOf":{"@id":"https:\/\/bsc-srl.it\/cms\/#website"},"datePublished":"2013-08-21T17:03:41+00:00","dateModified":"2022-07-13T12:43:18+00:00","breadcrumb":{"@id":"https:\/\/bsc-srl.it\/cms\/smaltimento-rifiuti-cimiteriali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bsc-srl.it\/cms\/smaltimento-rifiuti-cimiteriali\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bsc-srl.it\/cms\/smaltimento-rifiuti-cimiteriali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bsc-srl.it\/cms\/"},{"@type":"ListItem","position":2,"name":"Smaltimento rifiuti cimiteriali"}]},{"@type":"WebSite","@id":"https:\/\/bsc-srl.it\/cms\/#website","url":"https:\/\/bsc-srl.it\/cms\/","name":"bsc-srl.it","description":"","publisher":{"@id":"https:\/\/bsc-srl.it\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bsc-srl.it\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/bsc-srl.it\/cms\/#organization","name":"Bergamo servizi cimiteriali","url":"https:\/\/bsc-srl.it\/cms\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/bsc-srl.it\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/bsc-srl.it\/cms\/wp-content\/uploads\/2021\/02\/bsc-logo-1.png","contentUrl":"https:\/\/bsc-srl.it\/cms\/wp-content\/uploads\/2021\/02\/bsc-logo-1.png","width":261,"height":106,"caption":"Bergamo servizi cimiteriali"},"image":{"@id":"https:\/\/bsc-srl.it\/cms\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bsc-srl.it\/cms\/wp-json\/wp\/v2\/pages\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bsc-srl.it\/cms\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bsc-srl.it\/cms\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bsc-srl.it\/cms\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bsc-srl.it\/cms\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":0,"href":"https:\/\/bsc-srl.it\/cms\/wp-json\/wp\/v2\/pages\/57\/revisions"}],"wp:attachment":[{"href":"https:\/\/bsc-srl.it\/cms\/wp-json\/wp\/v2\/media?parent=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}